{"id":1929,"date":"2010-12-31T18:54:52","date_gmt":"2011-01-01T02:54:52","guid":{"rendered":"http:\/\/inner-voices.net\/fr\/?p=1929"},"modified":"2010-12-31T18:54:52","modified_gmt":"2011-01-01T02:54:52","slug":"le-vendredi-merci-de-tous-les-vendredis-merci-de-2010","status":"publish","type":"post","link":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/","title":{"rendered":"Le Vendredi Merci de tous les Vendredis Merci de 2010"},"content":{"rendered":"<p>\ufeff<a href=\"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg\" class=\"wp_lightbox\" rel=\"post_1929\"><img decoding=\"async\" class=\"alignleft size-full wp-image-1605\" title=\"Gratitude Friday\" src=\"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg\" alt=\"\" width=\"176\" height=\"175\" srcset=\"https:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg 252w, https:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge-150x150.jpg 150w\" sizes=\"(max-width: 176px) 100vw, 176px\" \/><\/a><em><span style=\"color: #3f3f3f;\"><small> <strong>Vendredi Merci<\/strong> est un rituel que j&#8217;ai mis en place afin d&#8217;avoir conscience chaque semaine des moments heureux pour lesquels j&#8217;\u00e9prouve de la reconnaissance. Je vous invite \u00e0 participer \u00e9galement afin de r\u00e9aliser \u00e0 quelle hauteur la Gratitude peut changer votre fa\u00e7on de voir votre vie. Pour en savoir plus, lisez mon <a href=\"http:\/\/inner-voices.net\/fr\/2009\/10\/27\/jintroduis-un-nouveau-rituel-gratitude-friday\/\" target=\"_blank\">post d&#8217;introduction<\/a>.<\/small><\/span><\/em><\/p>\n<p>A l&#8217;heure o\u00f9 je tape ces mots, il est environ 2h20 du matin en France, 1er Janvier 2011, alors je vous souhaite une excellente ann\u00e9e 2011. Qu&#8217;elle vous apporte tout ce dont vous avez besoin, confiance, amour, joie, amiti\u00e9s, rires, cr\u00e9ativit\u00e9s, sous, bonne sant\u00e9&#8230;.<\/p>\n<p>Cette ann\u00e9e fut tr\u00e8s dense pour moi et je la quitte avec une sensation d&#8217;accomplissement (cela tombe bien, c&#8217;\u00e9tait mon mot pour 2010).<br \/>\nJ&#8217;ai appris \u00e9norm\u00e9ment et me sens plus forte que lorsque j&#8217;ai quitt\u00e9 2009 il y a un an. Cela sera sans doute un long article rempli de liens, j&#8217;esp\u00e8re que vous le lirez en entier mais si ce n&#8217;est pas le cas je ne vous en voudrai pas. Mais par-dessus tout, je serais combl\u00e9e si vous partagiez avec moi quelques petites choses pour lesquelles vous \u00eates reconnaissant-e- en 2010 \ud83d\ude42<\/p>\n<p>En ces derni\u00e8res heures de 2010, je voudrais remercier l&#8217;Univers pour:<\/p>\n<ul>\n<li>Avoir mis sur ma route des personnes merveilleuses:\u00a0<strong><a href=\"http:\/\/www.jamieridlerstudios.ca\" target=\"_blank\">Jamie Ridler<\/a><\/strong> (et mes soeurs du Circe&#8217;s Circle), <strong><a href=\"http:\/\/dirtyfootprints-studio.com\" target=\"_blank\">Connie Hozvicka<\/a><\/strong> (et mes soeurs de BIG et Tribe), <strong><a href=\"http:\/\/www.journalgirl.com\" target=\"_blank\">Samantha Kira<\/a><\/strong>, <strong><a href=\"http:\/\/joannarothman.com\" target=\"_blank\">Jo Anna Rothman<\/a><\/strong>, mes copines cr\u00e9atives de l&#8217;autre bout du Canada, les femmes passant chaque fois que je participe au Souhait du Mercredi pour encourager mes r\u00eaves, \u00a0Je ne veux pas lister tout le monde, mais vous \u00eates dans mon coeur.<\/li>\n<li><img decoding=\"async\" class=\"size-medium wp-image-2052 alignright\" title=\"I am Meant To Shine\" src=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2010\/10\/MeantToShine-242x300.jpg\" alt=\"\" width=\"169\" height=\"210\" \/>M&#8217;avoir permis de repousser encore plus mes fronti\u00e8res; en ayant la possibilit\u00e9 de suivre des ateliers tr\u00e8s divers, en ligne (je pense \u00e0 &#8220;<a href=\"https:\/\/www.e-junkie.com\/ecom\/gb.php?cl=106661&amp;c=ib&amp;aff=131422\" target=\"_blank\">Taking Flight<\/a>&#8221; de Kelly Rae Roberts, aux classes de Connie sur <a href=\"http:\/\/www.dirtyfootprintsworkshops.com\/\" target=\"_blank\">DirtyFootprints Studio<\/a>, au\u00a0<a href=\"http:\/\/jamieridlerstudios.ca\/circes-circle\" target=\"_blank\">coaching cr\u00e9atif de Jamie<\/a>, au\u00a0<a href=\"http:\/\/www.receivingproject.com\/about-the-receiving-project\" target=\"_blank\">Receiving Project<\/a> de Jo Anna, aux quelques classes de <a href=\"http:\/\/www.julieprichard.com\/mixed-media-workshops\/\" target=\"_blank\">Julie Prichard<\/a> (&amp; Chris Cozen)). Sans oublier, \u00e9videmment, le cadeau de l&#8217;Univers pour mes 25 ans: l&#8217;atelier de deux jours de\u00a0<a href=\"http:\/\/inner-voices.net\/blog\/2010-09-28\/my-2-day-workshop-with-fearless-painter-jesse-reno\/\" target=\"_blank\">Jesse Reno<\/a>. Tout cela a enrichi qui je suis. Et aujourd&#8217;hui je n&#8217;ai plus peur de dire \u00e0 voix haute: JE SUIS UNE ARTISTE. Et je suis t\u00e9m\u00e9raire. Et je suis Belle. Oui je le suis. Et vous \u00e9galement.<\/li>\n<li>Ma maman est venue en vacances 5 semaines chez nous, cela nous a permis de f\u00eater son anniversaire ensemble. Nous avions vraiment besoin de nous revoir enfin et elle nous manque terriblement. C&#8217;\u00e9tait parfait.<\/li>\n<li>Mon beau-fr\u00e8re est revenu en vacances pour deux semaines et \u00e9tait \u00e0 nouveau l\u00e0 pour l&#8217;anniversaire de Grenouille, ses 5 ans. Nous esp\u00e8rons qu&#8217;il viendra tous les ans.<\/li>\n<li>Notre nouveau logement. Certes nous sommes toujours locataires mais ce logement nous convient beaucoup mieux que le pr\u00e9c\u00e9dent. Et ce qui ne g\u00e2che rien, nos voisins sont adorables.<\/li>\n<li>Mon livre prend enfin de s\u00e9rieuses formes. Gr\u00e2ce au Circe&#8217;s Circle j&#8217;ai de meilleures bases pour y parvenir.<\/li>\n<li>Grenouille est tr\u00e8s fi\u00e8re de savoir lire toute seule, avec un peu plus d&#8217;aisance chaque jour. Et d&#8217;\u00e9crire. Elle m&#8217;\u00e9pate au quotidien (malgr\u00e9 le fait qu&#8217;elle soit tellement passionn\u00e9e par la lecture que c&#8217;est sa top priorit\u00e9, devant tout, m\u00eame les choses vitales comme manger).<\/li>\n<li>Koala qui est toujours aussi c\u00e2line avec moi, mais qui est de plus en plus ind\u00e9pendante. Il lui tarde d&#8217;avoir 5 ans pour aller &#8220;\u00e0 la grande \u00e9cole&#8221; (elle a presque 4 ans).<\/li>\n<li>Mon Ch\u00e9ridoo a finalement \u00e9t\u00e9 pris dans l&#8217;emploi de ses r\u00eaves, dans le monde des jeux vid\u00e9os. Alors oui \u00e7a m&#8217;agace qu&#8217;il passe beaucoup plus de temps qu&#8217;avant \u00e0 jouer sur la ps3 mais le voir \u00e9panoui professionnellement n&#8217;a pas de prix. Il travaille beaucoup, et dur, mais il est heureux. Cela valait le coup d&#8217;attendre et de r\u00eaver.<\/li>\n<li>Les peintures que j&#8217;ai faites et que j&#8217;aime \u00e9norm\u00e9ment, qui me &#8220;WOW&#8221; litt\u00e9ralement, du genre &#8220;mais est-ce vraiment moi qui ai cr\u00e9\u00e9 \u00e7a ?!&#8221;. Oui. Mon but pour 2011 et d&#8217;avoir ce sentiment pour chacune de mes cr\u00e9ations, et de faire resentir aux gens &#8220;c&#8217;est ce qu&#8217;il me fallait&#8221;. J&#8217;ai des messages \u00e0 passer et suis reconnaissante d&#8217;avoir un jour mis ma peur de c\u00f4t\u00e9 niveau cr\u00e9ativiti\u00e9.<\/li>\n<li><a href=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2010\/10\/Uniqueness1.jpg\" class=\"wp_lightbox\" rel=\"post_1929\"><img decoding=\"async\" class=\"alignright size-medium wp-image-2031\" title=\"I accept and embrace my Uniqueness\" src=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2010\/10\/Uniqueness1-236x300.jpg\" alt=\"\" width=\"165\" height=\"210\" \/><\/a>Pour l&#8217;abondance qui afflue; ce n&#8217;\u00e9tait pas facile tous les jours mais nous (mon \u00e9poux et moi) avons enfin eu ce d\u00e9clic n\u00e9cessaire pour nous d\u00e9faire de nos blocages au niveau prosp\u00e9rit\u00e9 (et je ne parle pas que financi\u00e8rement); \u00e7a fait toute la diff\u00e9rence. Et cela sera multipli\u00e9 par au moins 10 en 2011 \ud83d\ude09<\/li>\n<li>Pour mon partenariat avec Hay House et tout ce que je re\u00e7ois de b\u00e9n\u00e9fique par ce biais.<\/li>\n<li>Pour Tchoo, ma machine \u00e0 coudre, qui ouvre devant moi de nouvelles perspectives cr\u00e9atives.<\/li>\n<li>Pour les amies que j&#8217;ai malheureusement perdues. Elles comptent toujours pour moi d&#8217;une certaine mani\u00e8re et je n&#8217;\u00e9prouve pas d&#8217;amertume pour ce qui s&#8217;est pass\u00e9. J&#8217;ai ainsi appris que m\u00eame lorsque l&#8217;on pense bien faire, on ne peut forcer les gens \u00e0 voir les choses comme nous (m\u00eame si c&#8217;est fait inconsciemment).<\/li>\n<li>Pour les vid\u00e9os hebdomadaires de Donna Downey, qu&#8217;elle appelle ses\u00a0<a href=\"http:\/\/donnadowney.typepad.com\/simply_me\/inspiration-wednesdays.html\" target=\"_blank\">Inspiration Wednesday<\/a>.<\/li>\n<li>Pour tous les super livres que j&#8217;ai lu tout au long de l&#8217;ann\u00e9e. Cela me transporte et parfois tititille un peu plus ma cr\u00e9ativit\u00e9, ce qui n&#8217;est pas du luxe.<\/li>\n<li>L&#8217;amour de et pour mon Grand A (terme \u00a9 Alice Kara. LOL !). Nous avons c\u00e9l\u00e9br\u00e9 nos 7 ans d&#8217;amour ainsi que nos 5 ans de mariage en 2010. Nous sommes plus forts chaque ann\u00e9e qui passe. Je suis b\u00e9nie de partager ma vie avec un homme aussi merveilleux que lui.<\/li>\n<li>Certaines amiti\u00e9s se sont encore un peu plus renforc\u00e9es (Je vous aime Alice, Paola, Sophie, Cocotte, Melchi).<\/li>\n<li>Les bonnes s\u00e9ries tv, bons films et la bonne musique qui remplissent mon univers au quotidien. Et les bons restaurants aussi (mais pas quotidiens, eux).<\/li>\n<li>La cuisine qui a fait son retour dans ma liste des choses_que_j&#8217;aime_beaucoup_faire.<\/li>\n<li>Vivre dans cette ville si diff\u00e9rente de ce que nous connaissions, Vancouver. C&#8217;est loin d&#8217;\u00eatre facile tous les jours, surtout sans famille lorsque l&#8217;on a deux jeunes enfants et que p\u00e9ter les plombs est encore plus facile car personne pour prendre le relais de temps en temps, ce n&#8217;est pas non plus facile de se faire de nouveaux amis. Mais nous n&#8217;avons aucun regret.<\/li>\n<\/ul>\n<p>Et tant d&#8217;autres choses encore&#8230;<\/p>\n<p>Cette ann\u00e9e fut tr\u00e8s difficile par moments, je ne vais pas le cacher. Mais dans son ensemble elle fut bonne et positive. Mon \u00e9volution est sur la bonne voie, je peux le sentir. Energ\u00e9tiquement, beaucoup de choses ont \u00e9t\u00e9 remu\u00e9es et nous avons \u00e9t\u00e9 quelque peu forc\u00e9s de prendre sur nous, de nous d\u00e9faire de notre pass\u00e9 et de faire des choix qui marqueront la route \u00e0 venir m\u00eame sans qu&#8217;on ne s\u00e2che encore comment. Mais nous nous rapprochons de la r\u00e9alisation de nos r\u00eaves, alors n&#8217;h\u00e9sitez pas \u00e0 les formuler clairement. Vous \u00eates \u00e9cout\u00e9s, et n&#8217;\u00eates jamais oubli\u00e9s.<\/p>\n<p>Je vous aime. Prenez bien soin de vous et de ceux que vous aimez.<\/p>\n<p>Bonne ann\u00e9e 2011 !!!<\/p>\n<p><em><span style=\"color: #2f4f4f;\">Vous avez \u00e9crit sur votre blog dans le cadre du Vendredi Merci ? N\u2019h\u00e9sitez pas \u00e0 mettre votre Nom et l\u2019URL de votre article ci-dessous: <\/span><\/em><br \/>\n[linkme]\n","protected":false},"excerpt":{"rendered":"<p>\ufeff Vendredi Merci est un rituel que j&#8217;ai mis en place afin d&#8217;avoir conscience chaque semaine des moments heureux pour lesquels j&#8217;\u00e9prouve de la reconnaissance. Je vous invite \u00e0 participer \u00e9galement afin de r\u00e9aliser \u00e0 quelle hauteur la Gratitude peut changer votre fa\u00e7on de voir votre vie. Pour en savoir plus, lisez mon post d&#8217;introduction. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"qubely_global_settings":"","qubely_interactions":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[42],"tags":[239],"class_list":["post-1929","post","type-post","status-publish","format-standard","hentry","category-vendredi-merci","tag-vendredi-merci"],"qubely_featured_image_url":null,"qubely_author":{"display_name":"Nolwenn","author_link":"https:\/\/inner-voices.net\/fr\/author\/nolwenn\/"},"qubely_comment":2,"qubely_category":"<a href=\"https:\/\/inner-voices.net\/fr\/category\/etre\/introspection\/vendredi-merci\/\" rel=\"category tag\">Vendredi Merci<\/a>","qubely_excerpt":"\ufeff Vendredi Merci est un rituel que j&#8217;ai mis en place afin d&#8217;avoir conscience chaque semaine des moments heureux pour lesquels j&#8217;\u00e9prouve de la reconnaissance. Je vous invite \u00e0 participer \u00e9galement afin de r\u00e9aliser \u00e0 quelle hauteur la Gratitude peut changer votre fa\u00e7on de voir votre vie. Pour en savoir plus, lisez mon post d&#8217;introduction.&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures\" \/>\n<meta property=\"og:description\" content=\"\ufeff Vendredi Merci est un rituel que j&#8217;ai mis en place afin d&#8217;avoir conscience chaque semaine des moments heureux pour lesquels j&#8217;\u00e9prouve de la reconnaissance. Je vous invite \u00e0 participer \u00e9galement afin de r\u00e9aliser \u00e0 quelle hauteur la Gratitude peut changer votre fa\u00e7on de voir votre vie. Pour en savoir plus, lisez mon post d&#8217;introduction. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Voix interieures\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-01T02:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg\" \/>\n<meta name=\"author\" content=\"Nolwenn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nolwennp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nolwenn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/\"},\"author\":{\"name\":\"Nolwenn\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\"},\"headline\":\"Le Vendredi Merci de tous les Vendredis Merci de 2010\",\"datePublished\":\"2011-01-01T02:54:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/\"},\"wordCount\":1259,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/inner-voices.net\\\/fr\\\/files\\\/2010\\\/07\\\/GratitudeFriday-Badge.jpg\",\"keywords\":[\"Vendredi Merci\"],\"articleSection\":[\"Vendredi Merci\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/\",\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/\",\"name\":\"Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/inner-voices.net\\\/fr\\\/files\\\/2010\\\/07\\\/GratitudeFriday-Badge.jpg\",\"datePublished\":\"2011-01-01T02:54:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#primaryimage\",\"url\":\"http:\\\/\\\/inner-voices.net\\\/fr\\\/files\\\/2010\\\/07\\\/GratitudeFriday-Badge.jpg\",\"contentUrl\":\"http:\\\/\\\/inner-voices.net\\\/fr\\\/files\\\/2010\\\/07\\\/GratitudeFriday-Badge.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2010\\\/12\\\/31\\\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Vendredi Merci de tous les Vendredis Merci de 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/\",\"name\":\"Voix interieures\",\"description\":\"Trouvez votre Voix Int\u00e9rieure \u00e0 travers la Cr\u00e9ativit\u00e9.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\",\"name\":\"Nolwenn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"caption\":\"Nolwenn\"},\"sameAs\":[\"http:\\\/\\\/inner-voices.net\",\"http:\\\/\\\/www.instagram.com\\\/nolwennp\",\"https:\\\/\\\/x.com\\\/nolwennp\"],\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/author\\\/nolwenn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures","og_description":"\ufeff Vendredi Merci est un rituel que j&#8217;ai mis en place afin d&#8217;avoir conscience chaque semaine des moments heureux pour lesquels j&#8217;\u00e9prouve de la reconnaissance. Je vous invite \u00e0 participer \u00e9galement afin de r\u00e9aliser \u00e0 quelle hauteur la Gratitude peut changer votre fa\u00e7on de voir votre vie. Pour en savoir plus, lisez mon post d&#8217;introduction. ...","og_url":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/","og_site_name":"Voix interieures","article_published_time":"2011-01-01T02:54:52+00:00","og_image":[{"url":"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg","type":"","width":"","height":""}],"author":"Nolwenn","twitter_card":"summary_large_image","twitter_creator":"@nolwennp","twitter_misc":{"Written by":"Nolwenn","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#article","isPartOf":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/"},"author":{"name":"Nolwenn","@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6"},"headline":"Le Vendredi Merci de tous les Vendredis Merci de 2010","datePublished":"2011-01-01T02:54:52+00:00","mainEntityOfPage":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/"},"wordCount":1259,"commentCount":2,"image":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#primaryimage"},"thumbnailUrl":"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg","keywords":["Vendredi Merci"],"articleSection":["Vendredi Merci"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/","url":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/","name":"Le Vendredi Merci de tous les Vendredis Merci de 2010 - Voix interieures","isPartOf":{"@id":"https:\/\/inner-voices.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#primaryimage"},"image":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#primaryimage"},"thumbnailUrl":"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg","datePublished":"2011-01-01T02:54:52+00:00","author":{"@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6"},"breadcrumb":{"@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#primaryimage","url":"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg","contentUrl":"http:\/\/inner-voices.net\/fr\/files\/2010\/07\/GratitudeFriday-Badge.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/inner-voices.net\/fr\/2010\/12\/31\/le-vendredi-merci-de-tous-les-vendredis-merci-de-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/inner-voices.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Vendredi Merci de tous les Vendredis Merci de 2010"}]},{"@type":"WebSite","@id":"https:\/\/inner-voices.net\/fr\/#website","url":"https:\/\/inner-voices.net\/fr\/","name":"Voix interieures","description":"Trouvez votre Voix Int\u00e9rieure \u00e0 travers la Cr\u00e9ativit\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inner-voices.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6","name":"Nolwenn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","caption":"Nolwenn"},"sameAs":["http:\/\/inner-voices.net","http:\/\/www.instagram.com\/nolwennp","https:\/\/x.com\/nolwennp"],"url":"https:\/\/inner-voices.net\/fr\/author\/nolwenn\/"}]}},"_links":{"self":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":2,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"predecessor-version":[{"id":1931,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/1929\/revisions\/1931"}],"wp:attachment":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}