{"id":2474,"date":"2011-12-31T21:22:44","date_gmt":"2012-01-01T05:22:44","guid":{"rendered":"http:\/\/inner-voices.net\/fr\/?p=2474"},"modified":"2011-12-31T21:22:44","modified_gmt":"2012-01-01T05:22:44","slug":"ce-que-2011-ma-appris","status":"publish","type":"post","link":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/","title":{"rendered":"Ce que 2011 m&#8217;a appris"},"content":{"rendered":"<p>Je sais, je sais&#8230; encore un autre post sur la blogosph\u00e8re au sujet de la nouvelle ann\u00e9e. Mais je pensais \u00e0 ce th\u00e8me depuis plus d&#8217;une semaine, ce que 2011 a mis sur ma route de positif comme de n\u00e9gatif, ne trouvant vraiment le temps de me poser pour \u00e9crire.<\/p>\n<p>Il me semble que je faisais <a title=\"Je ne prends pas de R\u00e9solutions mais j\u2019\u00e9mets des Intentions\" href=\"http:\/\/inner-voices.net\/fr\/2011\/01\/03\/je-ne-prends-pas-de-resolutions-mais-jemets-des-intentions\/\" target=\"_blank\">mes plans pour 2011<\/a>. Ai-je atteint tous mes buts ? Oh que non. Mais cela ne me d\u00e9range pas plus que cela finalement. Parce que j&#8217;ai ENORMEMENT appris au cours de ces douze derniers mois.<\/p>\n<p>Grace au <a href=\"http:\/\/www.goddessguidebook.com\/affiliate-redirect\/?w=2012cygy&amp;p=Nolwenn\" target=\"_blank\"><strong>planner de Leonie<\/strong><\/a>, que je remplis joyeusement, j&#8217;ai pu r\u00e9aliser en fin de compte \u00e0 quel point <big>mon ann\u00e9e fut jonch\u00e9e de r\u00e9ussites<\/big> (meme petites).<\/p>\n<p>J&#8217;ai ouvert ma boutique Etsy, <a href=\"http:\/\/InnerWorlds.etsy.com\" target=\"_blank\">Inner Worlds<\/a>, pouss\u00e9e doucement mais surement par mon amie <a href=\"http:\/\/www.dirtyfootprints-studio.com\" target=\"_blank\">Connie<\/a>. Ce fut un pas \u00e9norme en avant. Montrer mes cr\u00e9ations au monde entier, demander de l&#8217;argent en \u00e9change de mon art, qui est devenu mon travail et non plus une simple passion (j&#8217;ai encore quelques soucis avec le cot\u00e9 financier parfois). Et j&#8217;ai fait plusieurs ventes (je n&#8217;y croyais pas vraiment lorsque je me suis lanc\u00e9e).<\/p>\n<p><img decoding=\"async\" class=\"alignright size-thumbnail wp-image-2987\" title=\"20111231-082915.jpg\" src=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>En F\u00e9vrier, j&#8217;ai suivi mon intuition et ai commenc\u00e9 mon propre projet de 365-photo en un an, mais centr\u00e9 sur les auto-portraits, et j&#8217;ai simplement intitul\u00e9 ce projet mon &#8220;<a href=\"http:\/\/www.flickr.com\/photos\/nolwennp\/sets\/72157626248263919\/\" target=\"_blank\">365-selfportraits challenge<\/a>&#8220;, que j&#8217;ai d\u00e9but\u00e9 au 1er Mars. Et <big>cela m&#8217;a appris \u00e0 me voir diff\u00e9remment, \u00e0 atteindre une perspective diff\u00e9rente quant \u00e0 moi-meme.<\/big> Malgr\u00e9 le fait que je ne sois pas permanente, je continue ici et l\u00e0. Et je veux refaire un projet de ce style tout au long the 2012. Je ne sais juste pas si je reste centr\u00e9e sur ce th\u00e8me, ou si j&#8217;en fais un plus g\u00e9n\u00e9ral que je pourrai enti\u00e8rement partager avec vous. Je pense faire un projet de portraits de mes filles.<\/p>\n<p>J&#8217;ai appris qu&#8217;il y a croyance dans les mauvaises nouvelles entourant la sant\u00e9. Que malgr\u00e9 ce que beaucoup de gens pensent, la pens\u00e9e positive et le Reiki peuvent aider. Beaucoup. Meme contre le cancer.<br \/>\nJe suis maintenant Maitre en Practical Reiki et suis pleinement engag\u00e9e dans mon processus de gu\u00e9rison spirituelle et physique, et offre mes services \u00e0 qui en a besoin.<\/p>\n<p><big>2011 m&#8217;a appris \u00e0 faire confiance sinc\u00e8rement, sans doute, savoir dans mes trippes que tout va bien, et ira de mieux en mieux.<\/big><\/p>\n<p>J&#8217;ai appris \u00e0 donner mon amiti\u00e9, parfois \u00e0 nouveau. Malgr\u00e9 la douleur ressentie alors. Je donne des secondes chances. Mais il n&#8217;y aura pas de troisi\u00e8me (je sais reconnaitre mes torts du moment, cependant).<\/p>\n<p><a href=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/11\/2011-Growth.jpg\" class=\"wp_lightbox\" rel=\"post_2474\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2915\" title=\"Growth\" src=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/11\/2011-Growth-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>J&#8217;ai envoy\u00e9 mes souhaits \u00e0 l&#8217;Univers, et ai recu les r\u00e9ponses attendues. C&#8217;est ainsi que je suis all\u00e9e assister \u00e0 des ateliers \u00e0 Seattle, deux fois, \u00e0 l&#8217;Artfest Annex de <a href=\"http:\/\/www.teeshamoore.com\" target=\"_blank\">Teesha Moore<\/a>. Le premier pour un atelier avec Teesha elle-meme, pendant lequel j&#8217;ai rencontr\u00e9 mes amies alors virtuelles: <a href=\"http:\/\/www.violette.ca\" target=\"_blank\">Violette<\/a> et <a href=\"http:\/\/blissartworks.com\/Site\/Welcome.html\" target=\"_blank\">Kym<\/a>.<br \/>\nCes deux ateliers ont \u00e9t\u00e9 des tournants dans ma cr\u00e9ativit\u00e9.<\/p>\n<p>Comme vous le savez si vous me suivez sur Facebook, vous savez que cette peinture a \u00e9t\u00e9 r\u00e9alis\u00e9e pendant l&#8217;atelier de <a href=\"http:\/\/www.florasbowley.com\/\" target=\"_blank\">Flora Bowley<\/a> en novembre dernier. This painting was done during <a title=\"Still processing the awesomeness of Flora Bowley\u2019s \u201cBloom True\u201d workshop\" href=\"http:\/\/inner-voices.net\/blog\/2011-11-17\/still-processing-the-awesomeness-of-flora-bowleys-bloom-true-workshop\/\" target=\"_blank\">Flora Bowley&#8217;s workshop<\/a> et elle repr\u00e9sente beaucoup \u00e0 mes yeux. Je la regarde en me demandant comment moi, j&#8217;ai pu peindre cela. Moi. Elle est maintenant accroch\u00e9e sur notre mur, de facon \u00e0 ce que je la vois chaque fois que je franchis la porte d&#8217;entr\u00e9e, et quand je suis dans le salon.<\/p>\n<p>Beaucoup de symboles, un message qui correspond au mantra de ma vie. Mon coeur se trouve dans cette toile de 76x76cm. Dans ce lotus et autour. Meme sans Nixie \ud83d\ude09<\/p>\n<p>J&#8217;aime toutes les imperfections qui font de cette peinture ce qu&#8217;elle est. je tais la Vierge perfectionniste qui vit en moi&#8230;<\/p>\n<p>Cette ann\u00e9e m&#8217;a appris de ne jamais abandonner une passion. Je suis donc de retour \u00e0 l&#8217;\u00e9criture. Salvatrice. Purificatrice. Gu\u00e9risseuse. Ce livre qui prend vit en moi depuis plusieurs ann\u00e9es refait surface petit \u00e0 petit. Projet mis de cot\u00e9 pour pleins de diverses raisons. Les mots s&#8217;empilant les uns les autres au bout de mes doigts, restant dans mon coeur plutot que d&#8217;accepter d&#8217;etre couch\u00e9s sur le papier. Je sais qu&#8217;ils ne devraient pas rester silencieux. Qu&#8217;ils sont l\u00e0 pour etre partag\u00e9s. Un jour. Peut-etre que 2012 sera l&#8217;ann\u00e9e durant laquelle ils verront le jour. Mais pour le moment, je raconte tout simplement \u00e0 voix hautes les histoires que mes Nixies me susurent, des bouts d&#8217;elles, des morceaux de moi.<\/p>\n<p>2011 fut \u00e9motionnellement difficile. Apprendre \u00e0 dire adieu tout en \u00e9tant \u00e0 8,000km. Apprendre \u00e0 aimer de loin sans les vrais calins. Apprendre \u00e0 accepter que l&#8217;on ne peut tout controler. Mais ce fut une ann\u00e9e qui a ouvert mes yeux et mon coeur. Et c&#8217;est avec un immense <span style=\"color: #3333cc;\"><strong>MERCI<\/strong><\/span> que je la laisse partir et accueille 2012 dans quelques heures maintenant (en Europe, les douze coups de minuit ont d\u00e9j\u00e0 sonn\u00e9).<\/p>\n<p>Je vous souhaite \u00e0 tous et toutes une excellente nouvelle ann\u00e9e !!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je sais, je sais&#8230; encore un autre post sur la blogosph\u00e8re au sujet de la nouvelle ann\u00e9e. Mais je pensais \u00e0 ce th\u00e8me depuis plus d&#8217;une semaine, ce que 2011 a mis sur ma route de positif comme de n\u00e9gatif, ne trouvant vraiment le temps de me poser pour \u00e9crire. Il me semble que je &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"qubely_global_settings":"","qubely_interactions":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[107,34],"tags":[245,235,128],"class_list":["post-2474","post","type-post","status-publish","format-standard","hentry","category-etre","category-introspection","tag-etre","tag-introspection","tag-nouvelle-annee"],"qubely_featured_image_url":null,"qubely_author":{"display_name":"Nolwenn","author_link":"https:\/\/inner-voices.net\/fr\/author\/nolwenn\/"},"qubely_comment":2,"qubely_category":"<a href=\"https:\/\/inner-voices.net\/fr\/category\/etre\/\" rel=\"category tag\">\u00catre<\/a> <a href=\"https:\/\/inner-voices.net\/fr\/category\/etre\/introspection\/\" rel=\"category tag\">Introspection<\/a>","qubely_excerpt":"Je sais, je sais&#8230; encore un autre post sur la blogosph\u00e8re au sujet de la nouvelle ann\u00e9e. Mais je pensais \u00e0 ce th\u00e8me depuis plus d&#8217;une semaine, ce que 2011 a mis sur ma route de positif comme de n\u00e9gatif, ne trouvant vraiment le temps de me poser pour \u00e9crire. Il me semble que je&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ce que 2011 m&#039;a appris - Voix interieures<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce que 2011 m&#039;a appris - Voix interieures\" \/>\n<meta property=\"og:description\" content=\"Je sais, je sais&#8230; encore un autre post sur la blogosph\u00e8re au sujet de la nouvelle ann\u00e9e. Mais je pensais \u00e0 ce th\u00e8me depuis plus d&#8217;une semaine, ce que 2011 a mis sur ma route de positif comme de n\u00e9gatif, ne trouvant vraiment le temps de me poser pour \u00e9crire. Il me semble que je ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/\" \/>\n<meta property=\"og:site_name\" content=\"Voix interieures\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-01T05:22:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Nolwenn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nolwennp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nolwenn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/\"},\"author\":{\"name\":\"Nolwenn\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\"},\"headline\":\"Ce que 2011 m&#8217;a appris\",\"datePublished\":\"2012-01-01T05:22:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/\"},\"wordCount\":841,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/inner-voices.net\\\/wp-content\\\/uploads\\\/2011\\\/12\\\/20111231-082915-150x150.jpg\",\"keywords\":[\"\u00catre\",\"Introspection\",\"Nouvelle Ann\u00e9e\"],\"articleSection\":[\"\u00catre\",\"Introspection\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/\",\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/\",\"name\":\"Ce que 2011 m'a appris - Voix interieures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/inner-voices.net\\\/wp-content\\\/uploads\\\/2011\\\/12\\\/20111231-082915-150x150.jpg\",\"datePublished\":\"2012-01-01T05:22:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#primaryimage\",\"url\":\"http:\\\/\\\/inner-voices.net\\\/wp-content\\\/uploads\\\/2011\\\/12\\\/20111231-082915-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/inner-voices.net\\\/wp-content\\\/uploads\\\/2011\\\/12\\\/20111231-082915-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/2011\\\/12\\\/31\\\/ce-que-2011-ma-appris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ce que 2011 m&#8217;a appris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/\",\"name\":\"Voix interieures\",\"description\":\"Trouvez votre Voix Int\u00e9rieure \u00e0 travers la Cr\u00e9ativit\u00e9.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/#\\\/schema\\\/person\\\/db0aa57810e3544bc1baf42aebe03ae6\",\"name\":\"Nolwenn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g\",\"caption\":\"Nolwenn\"},\"sameAs\":[\"http:\\\/\\\/inner-voices.net\",\"http:\\\/\\\/www.instagram.com\\\/nolwennp\",\"https:\\\/\\\/x.com\\\/nolwennp\"],\"url\":\"https:\\\/\\\/inner-voices.net\\\/fr\\\/author\\\/nolwenn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ce que 2011 m'a appris - Voix interieures","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/","og_locale":"fr_FR","og_type":"article","og_title":"Ce que 2011 m'a appris - Voix interieures","og_description":"Je sais, je sais&#8230; encore un autre post sur la blogosph\u00e8re au sujet de la nouvelle ann\u00e9e. Mais je pensais \u00e0 ce th\u00e8me depuis plus d&#8217;une semaine, ce que 2011 a mis sur ma route de positif comme de n\u00e9gatif, ne trouvant vraiment le temps de me poser pour \u00e9crire. Il me semble que je ...","og_url":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/","og_site_name":"Voix interieures","article_published_time":"2012-01-01T05:22:44+00:00","og_image":[{"url":"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg","type":"","width":"","height":""}],"author":"Nolwenn","twitter_card":"summary_large_image","twitter_creator":"@nolwennp","twitter_misc":{"Written by":"Nolwenn","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#article","isPartOf":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/"},"author":{"name":"Nolwenn","@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6"},"headline":"Ce que 2011 m&#8217;a appris","datePublished":"2012-01-01T05:22:44+00:00","mainEntityOfPage":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/"},"wordCount":841,"commentCount":2,"image":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#primaryimage"},"thumbnailUrl":"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg","keywords":["\u00catre","Introspection","Nouvelle Ann\u00e9e"],"articleSection":["\u00catre","Introspection"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/","url":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/","name":"Ce que 2011 m'a appris - Voix interieures","isPartOf":{"@id":"https:\/\/inner-voices.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#primaryimage"},"image":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#primaryimage"},"thumbnailUrl":"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg","datePublished":"2012-01-01T05:22:44+00:00","author":{"@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6"},"breadcrumb":{"@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#primaryimage","url":"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg","contentUrl":"http:\/\/inner-voices.net\/wp-content\/uploads\/2011\/12\/20111231-082915-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/inner-voices.net\/fr\/2011\/12\/31\/ce-que-2011-ma-appris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/inner-voices.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Ce que 2011 m&#8217;a appris"}]},{"@type":"WebSite","@id":"https:\/\/inner-voices.net\/fr\/#website","url":"https:\/\/inner-voices.net\/fr\/","name":"Voix interieures","description":"Trouvez votre Voix Int\u00e9rieure \u00e0 travers la Cr\u00e9ativit\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inner-voices.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/inner-voices.net\/fr\/#\/schema\/person\/db0aa57810e3544bc1baf42aebe03ae6","name":"Nolwenn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e66a53a034a32f2b2a8eb010d24fdb1d67b068229796082fabc79ed886c7a8b?s=96&d=identicon&r=g","caption":"Nolwenn"},"sameAs":["http:\/\/inner-voices.net","http:\/\/www.instagram.com\/nolwennp","https:\/\/x.com\/nolwennp"],"url":"https:\/\/inner-voices.net\/fr\/author\/nolwenn\/"}]}},"_links":{"self":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/2474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/comments?post=2474"}],"version-history":[{"count":1,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/2474\/revisions"}],"predecessor-version":[{"id":2475,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/posts\/2474\/revisions\/2475"}],"wp:attachment":[{"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/media?parent=2474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/categories?post=2474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inner-voices.net\/fr\/wp-json\/wp\/v2\/tags?post=2474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}